{"id":20682,"date":"2025-01-10T12:07:16","date_gmt":"2025-01-10T11:07:16","guid":{"rendered":"https:\/\/www.snav.it\/wp-content\/uploads\/2025\/01\/Slider-1.png"},"modified":"2025-01-10T12:07:16","modified_gmt":"2025-01-10T11:07:16","slug":"slider-3-2","status":"inherit","type":"attachment","link":"https:\/\/snav.test3d0.it\/hr\/slider-3-2","title":{"rendered":"Slider"},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-20682","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/snav.test3d0.it\/wp-content\/uploads\/2025\/01\/Slider-1.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"94\" src=\"https:\/\/snav.test3d0.it\/wp-content\/uploads\/2025\/01\/Slider-1-300x94.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/snav.test3d0.it\/wp-content\/uploads\/2025\/01\/Slider-1-300x94.png 300w, https:\/\/snav.test3d0.it\/wp-content\/uploads\/2025\/01\/Slider-1-1024x320.png 1024w, https:\/\/snav.test3d0.it\/wp-content\/uploads\/2025\/01\/Slider-1-768x240.png 768w, https:\/\/snav.test3d0.it\/wp-content\/uploads\/2025\/01\/Slider-1-1536x480.png 1536w, https:\/\/snav.test3d0.it\/wp-content\/uploads\/2025\/01\/Slider-1-672x210.png 672w, https:\/\/snav.test3d0.it\/wp-content\/uploads\/2025\/01\/Slider-1-1038x325.png 1038w, https:\/\/snav.test3d0.it\/wp-content\/uploads\/2025\/01\/Slider-1-480x150.png 480w, https:\/\/snav.test3d0.it\/wp-content\/uploads\/2025\/01\/Slider-1.png 1999w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":1999,"height":625,"file":"2025\/01\/Slider-1.png","filesize":2369966,"sizes":{"medium":{"file":"Slider-1-300x94.png","width":300,"height":94,"filesize":53924,"mime_type":"image\/png","source_url":"https:\/\/snav.test3d0.it\/wp-content\/uploads\/2025\/01\/Slider-1-300x94.png"},"large":{"file":"Slider-1-1024x320.png","width":1024,"height":320,"filesize":507342,"mime_type":"image\/png","source_url":"https:\/\/snav.test3d0.it\/wp-content\/uploads\/2025\/01\/Slider-1-1024x320.png"},"thumbnail":{"file":"Slider-1-150x150.png","width":150,"height":150,"filesize":40385,"mime_type":"image\/png","source_url":"https:\/\/snav.test3d0.it\/wp-content\/uploads\/2025\/01\/Slider-1-150x150.png"},"medium_large":{"file":"Slider-1-768x240.png","width":768,"height":240,"filesize":302712,"mime_type":"image\/png","source_url":"https:\/\/snav.test3d0.it\/wp-content\/uploads\/2025\/01\/Slider-1-768x240.png"},"1536x1536":{"file":"Slider-1-1536x480.png","width":1536,"height":480,"filesize":1030451,"mime_type":"image\/png","source_url":"https:\/\/snav.test3d0.it\/wp-content\/uploads\/2025\/01\/Slider-1-1536x480.png"},"post-thumbnail":{"file":"Slider-1-672x210.png","width":672,"height":210,"filesize":237050,"mime_type":"image\/png","source_url":"https:\/\/snav.test3d0.it\/wp-content\/uploads\/2025\/01\/Slider-1-672x210.png"},"kleo-full-width":{"file":"Slider-1-1038x325.png","width":1038,"height":325,"filesize":521446,"mime_type":"image\/png","source_url":"https:\/\/snav.test3d0.it\/wp-content\/uploads\/2025\/01\/Slider-1-1038x325.png"},"kleo-post-gallery":{"file":"Slider-1-480x270.png","width":480,"height":270,"filesize":206082,"mime_type":"image\/png","source_url":"https:\/\/snav.test3d0.it\/wp-content\/uploads\/2025\/01\/Slider-1-480x270.png"},"kleo-post-grid":{"file":"Slider-1-480x150.png","width":480,"height":150,"filesize":127387,"mime_type":"image\/png","source_url":"https:\/\/snav.test3d0.it\/wp-content\/uploads\/2025\/01\/Slider-1-480x150.png"},"kleo-post-small-thumb":{"file":"Slider-1-480x270.png","width":480,"height":270,"filesize":206082,"mime_type":"image\/png","source_url":"https:\/\/snav.test3d0.it\/wp-content\/uploads\/2025\/01\/Slider-1-480x270.png"},"gform-image-choice-sm":{"file":"Slider-1-300x300.png","width":300,"height":300,"filesize":142371,"mime_type":"image\/png","source_url":"https:\/\/snav.test3d0.it\/wp-content\/uploads\/2025\/01\/Slider-1-300x300.png"},"gform-image-choice-md":{"file":"Slider-1-400x400.png","width":400,"height":400,"filesize":237476,"mime_type":"image\/png","source_url":"https:\/\/snav.test3d0.it\/wp-content\/uploads\/2025\/01\/Slider-1-400x400.png"},"gform-image-choice-lg":{"file":"Slider-1-600x600.png","width":600,"height":600,"filesize":476488,"mime_type":"image\/png","source_url":"https:\/\/snav.test3d0.it\/wp-content\/uploads\/2025\/01\/Slider-1-600x600.png"},"full":{"file":"Slider-1.png","width":1999,"height":625,"mime_type":"image\/png","source_url":"https:\/\/snav.test3d0.it\/wp-content\/uploads\/2025\/01\/Slider-1.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/snav.test3d0.it\/wp-content\/uploads\/2025\/01\/Slider-1.png","_links":{"self":[{"href":"https:\/\/snav.test3d0.it\/hr\/wp-json\/wp\/v2\/media\/20682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/snav.test3d0.it\/hr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/snav.test3d0.it\/hr\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/snav.test3d0.it\/hr\/wp-json\/wp\/v2\/users\/6"}]}}